{"id":947,"date":"2017-09-24T15:41:41","date_gmt":"2017-09-24T15:41:41","guid":{"rendered":"http:\/\/www.celebratelife18.com\/?page_id=947"},"modified":"2021-08-19T01:17:28","modified_gmt":"2021-08-19T01:17:28","slug":"boxes-celebrate-bar-bat-mitvah","status":"publish","type":"page","link":"http:\/\/www.celebratelife18.com\/index.php\/boxes-celebrate-bar-bat-mitvah\/","title":{"rendered":"Boxes to Celebrate Bar and Bat Mitzvah"},"content":{"rendered":"<h2>Hinged Wooden Keepsake Boxes with Tile Inserts<\/h2>\n<p>These lined, square boxes measure 5 X 5 X 2.75 inches. \u00a0The tile inserts allow ample room for hand painted designs and personalized calligraphy.<\/p>\n<p><strong>Pricing for hinged wooden boxes begins at $85.00<\/strong><\/p>\n<p><a href=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Judaica-BarBatMitzvah-Celebration-Gift.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-961\" src=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Judaica-BarBatMitzvah-Celebration-Gift-300x300.jpg\" alt=\"Hand Painted Personalized Judaica wood box porcelain Bar and Bat Mitzvah Celebration\" width=\"300\" height=\"300\" srcset=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Judaica-BarBatMitzvah-Celebration-Gift-300x300.jpg 300w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Judaica-BarBatMitzvah-Celebration-Gift-150x150.jpg 150w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Judaica-BarBatMitzvah-Celebration-Gift-768x768.jpg 768w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Judaica-BarBatMitzvah-Celebration-Gift-1024x1024.jpg 1024w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Judaica-BarBatMitzvah-Celebration-Gift-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BarMitzvah1.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-962\" src=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BarMitzvah1-294x300.jpg\" alt=\"Hand Painted Personalized Judaica wood box porcelain Bar and Bat Mitzvah Celebration\" width=\"294\" height=\"300\" srcset=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BarMitzvah1-294x300.jpg 294w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BarMitzvah1.jpg 471w\" sizes=\"(max-width: 294px) 100vw, 294px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BarMitzvah4twin-1.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-963\" src=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BarMitzvah4twin-1-300x278.jpg\" alt=\"Hand Painted Personalized Judaica wood box porcelain Bar and Bat Mitzvah Celebration\" width=\"323\" height=\"300\" srcset=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BarMitzvah4twin-1-300x278.jpg 300w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BarMitzvah4twin-1-768x713.jpg 768w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BarMitzvah4twin-1-1024x950.jpg 1024w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BarMitzvah4twin-1.jpg 1536w\" sizes=\"(max-width: 323px) 100vw, 323px\" \/><\/a> <a href=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BatMitzvah5.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-964\" src=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BatMitzvah5-300x281.jpg\" alt=\"Hand Painted Personalized Judaica wood box porcelain Bar and Bat Mitzvah Celebration\" width=\"321\" height=\"300\" srcset=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BatMitzvah5-300x281.jpg 300w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BatMitzvah5-768x719.jpg 768w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BatMitzvah5-1024x958.jpg 1024w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BatMitzvah5.jpg 1536w\" sizes=\"(max-width: 321px) 100vw, 321px\" \/><\/a><\/p>\n<p><a href=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BatMitzvah6.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-965\" src=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BatMitzvah6-283x300.jpg\" alt=\"Hand Painted Personalized Judaica wood box porcelain Bar and Bat Mitzvah Celebration\" width=\"283\" height=\"300\" srcset=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BatMitzvah6-283x300.jpg 283w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BatMitzvah6.jpg 452w\" sizes=\"(max-width: 283px) 100vw, 283px\" \/><\/a> <a href=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BatMitzvah3.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-967\" src=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BatMitzvah3-300x289.jpg\" alt=\"Hand Painted Personalized Judaica wood box porcelain Bar and Bat Mitzvah Celebration\" width=\"311\" height=\"300\" srcset=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BatMitzvah3-300x289.jpg 300w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Personalized-Judaica-BatMitzvah3.jpg 480w\" sizes=\"(max-width: 311px) 100vw, 311px\" \/><\/a><\/p>\n<h2>Porcelain Trinket Boxes<\/h2>\n<p>These boxes are available in various shapes and sizes. \u00a0All surfaces can be painted with design and calligraphy for a special gift.<\/p>\n<p><a href=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1a.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-976\" src=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1a-300x300.jpg\" alt=\"HandPainted-Personalized-Porcelain-Judaica-Bat MitzvahBox\" width=\"300\" height=\"300\" srcset=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1a-300x300.jpg 300w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1a-150x150.jpg 150w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1a-768x768.jpg 768w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1a-1024x1024.jpg 1024w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1a-100x100.jpg 100w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1a.jpg 1188w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\u00a0<a href=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1b.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-977\" src=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1b-203x300.jpg\" alt=\"HandPainted-Personalized-Porcelain-Judaica-Bat MitzvahBox\" width=\"203\" height=\"300\" srcset=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1b-203x300.jpg 203w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1b-768x1133.jpg 768w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1b-694x1024.jpg 694w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1b.jpg 1521w\" sizes=\"(max-width: 203px) 100vw, 203px\" \/><\/a><\/p>\n<p style=\"text-align: left;\"><a href=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1c.jpg\">\u00a0<\/a><a href=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1c.jpg\">\u00a0<\/a><a href=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1c.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-978\" src=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1c-300x153.jpg\" alt=\"HandPainted-Personalized-Porcelain-Judaica-Bat MitzvahBox1\" width=\"501\" height=\"255\" srcset=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1c-300x153.jpg 300w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1c-768x391.jpg 768w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox1c-1024x522.jpg 1024w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/a><a href=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox2b.jpg\">\u00a0<\/a><\/p>\n<p style=\"text-align: left;\"><a href=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox2b.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-987\" src=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox2b-300x122.jpg\" alt=\"HandPainted-Personalized-Porcelain-Judaica-Bat MitzvahBox2a\" width=\"740\" height=\"300\" srcset=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox2b-300x122.jpg 300w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox2b-768x311.jpg 768w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox2b-1024x415.jpg 1024w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox2b.jpg 2044w\" sizes=\"(max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><\/a><\/p>\n<p style=\"text-align: left;\"><a href=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox2c.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-988\" src=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox2c-300x127.jpg\" alt=\"HandPainted-Personalized-Porcelain-Judaica-Bat MitzvahBox\" width=\"709\" height=\"300\" srcset=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox2c-300x127.jpg 300w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox2c-768x325.jpg 768w, http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/HandPainted-Personalized-Porcelain-Judaica-Bat-MitzvahBox2c-1024x433.jpg 1024w\" sizes=\"(max-width: 709px) 100vw, 709px\" \/><\/a><\/p>\n<p><strong>Pricing for porcelain boxes begins at $75.00.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hinged Wooden Keepsake Boxes with Tile Inserts These lined, square boxes measure 5 X 5 X 2.75 inches. \u00a0The tile inserts allow ample room for hand painted designs and personalized calligraphy. Pricing for hinged wooden boxes begins at $85.00 Porcelain Trinket Boxes These boxes are available in various shapes and sizes. \u00a0All surfaces can be &hellip; <\/p>\n<p class=\"link-more\"><a href=\"http:\/\/www.celebratelife18.com\/index.php\/boxes-celebrate-bar-bat-mitvah\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Boxes to Celebrate Bar and Bat Mitzvah&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Boxes to Celebrate Bar and Bat Mitzvah - Celebrate Life 18<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"http:\/\/www.celebratelife18.com\/index.php\/boxes-celebrate-bar-bat-mitvah\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Boxes to Celebrate Bar and Bat Mitzvah - Celebrate Life 18\" \/>\r\n<meta property=\"og:description\" content=\"Hinged Wooden Keepsake Boxes with Tile Inserts These lined, square boxes measure 5 X 5 X 2.75 inches. \u00a0The tile inserts allow ample room for hand painted designs and personalized calligraphy. Pricing for hinged wooden boxes begins at $85.00 Porcelain Trinket Boxes These boxes are available in various shapes and sizes. \u00a0All surfaces can be &hellip; Continue reading &quot;Boxes to Celebrate Bar and Bat Mitzvah&quot;\" \/>\r\n<meta property=\"og:url\" content=\"http:\/\/www.celebratelife18.com\/index.php\/boxes-celebrate-bar-bat-mitvah\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Celebrate Life 18\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CelebrateLife18ArtbyJanisWeisberg\" \/>\r\n<meta property=\"article:modified_time\" content=\"2021-08-19T01:17:28+00:00\" \/>\r\n<meta property=\"og:image\" content=\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Judaica-BarBatMitzvah-Celebration-Gift-300x300.jpg\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.celebratelife18.com\/index.php\/boxes-celebrate-bar-bat-mitvah\/\",\"url\":\"http:\/\/www.celebratelife18.com\/index.php\/boxes-celebrate-bar-bat-mitvah\/\",\"name\":\"Boxes to Celebrate Bar and Bat Mitzvah - Celebrate Life 18\",\"isPartOf\":{\"@id\":\"http:\/\/www.celebratelife18.com\/#website\"},\"datePublished\":\"2017-09-24T15:41:41+00:00\",\"dateModified\":\"2021-08-19T01:17:28+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/www.celebratelife18.com\/index.php\/boxes-celebrate-bar-bat-mitvah\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.celebratelife18.com\/index.php\/boxes-celebrate-bar-bat-mitvah\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.celebratelife18.com\/index.php\/boxes-celebrate-bar-bat-mitvah\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/www.celebratelife18.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boxes to Celebrate Bar and Bat Mitzvah\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.celebratelife18.com\/#website\",\"url\":\"http:\/\/www.celebratelife18.com\/\",\"name\":\"Celebrate Life 18\",\"description\":\"Hand Painted Porcelain~Jewelry with Spiritual Meaning~Specializing in Judaica\",\"publisher\":{\"@id\":\"http:\/\/www.celebratelife18.com\/#\/schema\/person\/6028ee1a0282dce572efa628b4b018a5\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.celebratelife18.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"http:\/\/www.celebratelife18.com\/#\/schema\/person\/6028ee1a0282dce572efa628b4b018a5\",\"name\":\"k8marley\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\/\/www.celebratelife18.com\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/10\/CelebrateLife18-logo-250x254.jpg\",\"contentUrl\":\"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/10\/CelebrateLife18-logo-250x254.jpg\",\"width\":250,\"height\":254,\"caption\":\"k8marley\"},\"logo\":{\"@id\":\"http:\/\/www.celebratelife18.com\/#\/schema\/person\/image\/\"},\"sameAs\":[\"http:\/\/www.celebratelife18.com\",\"https:\/\/www.facebook.com\/CelebrateLife18ArtbyJanisWeisberg\",\"https:\/\/www.instagram.com\/janis.weisberg.art\/?hl=en\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boxes to Celebrate Bar and Bat Mitzvah - Celebrate Life 18","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.celebratelife18.com\/index.php\/boxes-celebrate-bar-bat-mitvah\/","og_locale":"en_US","og_type":"article","og_title":"Boxes to Celebrate Bar and Bat Mitzvah - Celebrate Life 18","og_description":"Hinged Wooden Keepsake Boxes with Tile Inserts These lined, square boxes measure 5 X 5 X 2.75 inches. \u00a0The tile inserts allow ample room for hand painted designs and personalized calligraphy. Pricing for hinged wooden boxes begins at $85.00 Porcelain Trinket Boxes These boxes are available in various shapes and sizes. \u00a0All surfaces can be &hellip; Continue reading \"Boxes to Celebrate Bar and Bat Mitzvah\"","og_url":"http:\/\/www.celebratelife18.com\/index.php\/boxes-celebrate-bar-bat-mitvah\/","og_site_name":"Celebrate Life 18","article_publisher":"https:\/\/www.facebook.com\/CelebrateLife18ArtbyJanisWeisberg","article_modified_time":"2021-08-19T01:17:28+00:00","og_image":[{"url":"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/09\/WoodBox-Judaica-BarBatMitzvah-Celebration-Gift-300x300.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.celebratelife18.com\/index.php\/boxes-celebrate-bar-bat-mitvah\/","url":"http:\/\/www.celebratelife18.com\/index.php\/boxes-celebrate-bar-bat-mitvah\/","name":"Boxes to Celebrate Bar and Bat Mitzvah - Celebrate Life 18","isPartOf":{"@id":"http:\/\/www.celebratelife18.com\/#website"},"datePublished":"2017-09-24T15:41:41+00:00","dateModified":"2021-08-19T01:17:28+00:00","breadcrumb":{"@id":"http:\/\/www.celebratelife18.com\/index.php\/boxes-celebrate-bar-bat-mitvah\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.celebratelife18.com\/index.php\/boxes-celebrate-bar-bat-mitvah\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.celebratelife18.com\/index.php\/boxes-celebrate-bar-bat-mitvah\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.celebratelife18.com\/"},{"@type":"ListItem","position":2,"name":"Boxes to Celebrate Bar and Bat Mitzvah"}]},{"@type":"WebSite","@id":"http:\/\/www.celebratelife18.com\/#website","url":"http:\/\/www.celebratelife18.com\/","name":"Celebrate Life 18","description":"Hand Painted Porcelain~Jewelry with Spiritual Meaning~Specializing in Judaica","publisher":{"@id":"http:\/\/www.celebratelife18.com\/#\/schema\/person\/6028ee1a0282dce572efa628b4b018a5"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.celebratelife18.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"http:\/\/www.celebratelife18.com\/#\/schema\/person\/6028ee1a0282dce572efa628b4b018a5","name":"k8marley","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/www.celebratelife18.com\/#\/schema\/person\/image\/","url":"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/10\/CelebrateLife18-logo-250x254.jpg","contentUrl":"http:\/\/www.celebratelife18.com\/wp-content\/uploads\/2017\/10\/CelebrateLife18-logo-250x254.jpg","width":250,"height":254,"caption":"k8marley"},"logo":{"@id":"http:\/\/www.celebratelife18.com\/#\/schema\/person\/image\/"},"sameAs":["http:\/\/www.celebratelife18.com","https:\/\/www.facebook.com\/CelebrateLife18ArtbyJanisWeisberg","https:\/\/www.instagram.com\/janis.weisberg.art\/?hl=en"]}]}},"_links":{"self":[{"href":"http:\/\/www.celebratelife18.com\/index.php\/wp-json\/wp\/v2\/pages\/947"}],"collection":[{"href":"http:\/\/www.celebratelife18.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.celebratelife18.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.celebratelife18.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.celebratelife18.com\/index.php\/wp-json\/wp\/v2\/comments?post=947"}],"version-history":[{"count":23,"href":"http:\/\/www.celebratelife18.com\/index.php\/wp-json\/wp\/v2\/pages\/947\/revisions"}],"predecessor-version":[{"id":1890,"href":"http:\/\/www.celebratelife18.com\/index.php\/wp-json\/wp\/v2\/pages\/947\/revisions\/1890"}],"wp:attachment":[{"href":"http:\/\/www.celebratelife18.com\/index.php\/wp-json\/wp\/v2\/media?parent=947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}